{"id":7409,"date":"2021-12-14T00:01:17","date_gmt":"2021-12-13T23:01:17","guid":{"rendered":"https:\/\/manpowergroup.be\/?p=7409"},"modified":"2021-12-14T09:34:33","modified_gmt":"2021-12-14T08:34:33","slug":"les-employeurs-belges-prevoient-de-maintenir-un-rythme-dembauche-tres-soutenu-au-cours-du-1er-trimestre-2022","status":"publish","type":"post","link":"https:\/\/manpowergroup.be\/fr\/2021\/12\/14\/les-employeurs-belges-prevoient-de-maintenir-un-rythme-dembauche-tres-soutenu-au-cours-du-1er-trimestre-2022\/","title":{"rendered":"Les employeurs belges pr\u00e9voient de maintenir un rythme d\u2019embauche tr\u00e8s soutenu  au cours du 1er trimestre 2022"},"content":{"rendered":"<h3 style=\"text-align: center;\">Pr\u00e8s d\u2019un employeur sur deux (48%) pr\u00e9voit des embauches au 1<sup>er<\/sup> trimestre 2022, selon le Barom\u00e8tre de l\u2019emploi de ManpowerGroup<\/h3>\n<p>&nbsp;<\/p>\n<p>Selon le Barom\u00e8tre de ManpowerGroup \u2013 qui c\u00e9l\u00e8bre son 60<sup>e<\/sup> anniversaire au niveau mondial \u2013 <strong>la reprise sur le march\u00e9 de l\u2019emploi en Belgique, accompagn\u00e9e d\u2019une transformation de l\u2019\u00e9conomie, devrait se poursuivre au cours du 1<sup>er<\/sup> trimestre 2022.<\/strong><\/p>\n<p><strong>Sur les 505 employeurs belges sond\u00e9s en octobre par ManpowerGroup<\/strong><sup> (1),<\/sup> <strong>48%<\/strong> pr\u00e9voient d\u2019augmenter leurs effectifs d\u2019ici la fin du mois de mars 2022, tandis que seulement <strong>14%<\/strong> d\u2019entre eux pr\u00e9voient de les r\u00e9duire. <strong>36%<\/strong> des employeurs interrog\u00e9s n\u2019anticipent aucun changement. Apr\u00e8s correction des variations saisonni\u00e8res, <strong>la Pr\u00e9vision Nette d\u2019Emploi<\/strong><sup> (2) <\/sup>\u2013 ou le diff\u00e9rentiel entre le pourcentage d\u2019employeurs pr\u00e9voyant des embauches et le pourcentage de ceux pr\u00e9voyant des licenciements \u2013 <strong>atteint la valeur tr\u00e8s optimiste de +34%, en progression pour le sixi\u00e8me trimestre cons\u00e9cutif.<\/strong> C\u2019est une hausse de 4 points par rapport au trimestre pr\u00e9c\u00e9dent et de 28 points par rapport au 1<sup>er<\/sup> trimestre 2021. \u00a0Il s\u2019agit de la Pr\u00e9vision Nette d\u2019Emploi la plus \u00e9lev\u00e9e jamais enregistr\u00e9e depuis le lancement du Barom\u00e8tre de ManpowerGroup en Belgique en 2003.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-7429 size-full\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR.png\" alt=\"\" width=\"2401\" height=\"1255\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR.png 2401w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR-300x157.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR-1024x535.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR-768x401.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR-1536x803.png 1536w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR-2048x1070.png 2048w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR-260x136.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR-50x26.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/04_NEO_Outlook_-Belgium_-MEOS_Q122_-BEFR-143x75.png 143w\" sizes=\"(max-width: 2401px) 100vw, 2401px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00ab M\u00eame si l\u2019<strong>incertitude<\/strong> plane \u00e0 nouveau sur le march\u00e9 de l\u2019emploi en raison de la quatri\u00e8me vague du coronavirus, nous pouvons nous attendre \u00e0 ce que les employeurs continuent \u00e0 recruter \u00e0 un rythme tr\u00e8s soutenu au cours du 1<sup>er<\/sup> trimestre 2022 \u00bb<\/em><em> explique <\/em>Philippe Lacroix, Managing Director de ManpowerGroup BeLux.<\/p>\n<p><em>\u00ab <strong>Plusieurs raisons nous poussent \u00e0 rester confiants,<\/strong> alors que la troisi\u00e8me dose de la campagne de vaccination devrait s\u2019acc\u00e9l\u00e9rer. <strong>Premi\u00e8rement<\/strong>, <strong>notre \u00e9conomie a retrouv\u00e9 son niveau de croissance d\u2019avant la crise et poursuit sa transformation rapide.\u00a0<\/strong> Notre enqu\u00eate montre que la demande pour les profils digitaux n\u2019a jamais \u00e9t\u00e9 aussi \u00e9lev\u00e9e, les employeurs du secteur <\/em>\u2018<em>IT, Technologie, T\u00e9l\u00e9coms, Communication &amp; M\u00e9dias\u2019 \u2018rapportant la Pr\u00e9vision Nette d\u2019Emploi la plus forte de tous les secteurs sond\u00e9s (+53%). <\/em><em><strong>Deuxi\u00e8mement, les intentions de recrutement sont positives dans tous les secteurs sond\u00e9s,<\/strong> avec des pr\u00e9visions tr\u00e8s encourageantes\u00a0 dans les secteurs des \u00a0Banques et assurances, de la Construction, du Commerce et du Transport &amp; Logistique ou de l\u2019Industrie manufacturi\u00e8re. Enfin, \u00a0<strong>troisi\u00e8mement<\/strong>, de fa\u00e7on plus structurelle, <strong>le march\u00e9 de l\u2018emploi doit faire face au <\/strong><\/em><strong><em>d\u00e9part de la g\u00e9n\u00e9ration des boomers, n\u00e9s entre 1943 et 1960, ce qui <\/em><\/strong><em><strong>cr\u00e9e une activit\u00e9 de recrutement suppl\u00e9mentaire.<\/strong> Mais dans le m\u00eame temps, cela exacerbe les tensions au niveau des p\u00e9nuries de talents et renforce la pression sur les salaires. \u00bb<\/em><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-7432 size-full\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR.png\" alt=\"\" width=\"2401\" height=\"1255\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR.png 2401w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR-300x157.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR-1024x535.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR-768x401.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR-1536x803.png 1536w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR-2048x1070.png 2048w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR-260x136.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR-50x26.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/05_Historic_NEO_-Outlook_-Belgium_-MEOS_Q122_-BEFR-143x75.png 143w\" sizes=\"(max-width: 2401px) 100vw, 2401px\" \/><\/a><\/p>\n<h2><\/h2>\n<h2><strong>Intentions de recrutement plus fortes \u00e0 Bruxelles et en Flandre <\/strong><\/h2>\n<p>Les employeurs anticipent des <strong>perspectives d\u2019emploi positives dans les trois r\u00e9gions<\/strong> au cours du prochain trimestre. La confiance des employeurs est cependant nettement plus forte \u00e0 <strong>Bruxelles (+42%)<\/strong> et en <strong>Flandre (+40%)<\/strong> qu\u2019en <strong>Wallonie (+20%)<\/strong> o\u00f9 la Pr\u00e9vision Nette d\u2019Emploi perd 13 points par rapport au trimestre pr\u00e9c\u00e9dent.<\/p>\n<h2><\/h2>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-7435 size-full\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR.png\" alt=\"\" width=\"2401\" height=\"1255\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR.png 2401w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR-300x157.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR-1024x535.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR-768x401.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR-1536x803.png 1536w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR-2048x1070.png 2048w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR-260x136.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR-50x26.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/06_NEO_Outlook_-regions_-MEOS_Q122_-BEFR-143x75.png 143w\" sizes=\"(max-width: 2401px) 100vw, 2401px\" \/><\/a><\/p>\n<h2><\/h2>\n<h2><strong>Perspectives d\u2019emploi positives dans tous les 10 secteurs sond\u00e9s, le secteur IT tirant les cr\u00e9ations d\u2019emplois<\/strong><\/h2>\n<p>Les employeurs de tous les 10 secteurs d\u2019activit\u00e9 sond\u00e9s par ManpowerGroup anticipent des cr\u00e9ations d\u2019emploi au cours du 1<sup>er<\/sup> trimestre 2022. <strong>Le climat d\u2019embauche devrait s\u2019am\u00e9liorer dans six secteurs par rapport au trimestre pr\u00e9c\u00e9dent et dans tous les secteurs par rapport au 1<sup>er<\/sup> trimestre 2021.<\/strong><\/p>\n<p>Ce sont les employeurs du secteur \u2018<strong>IT, Technologie, T\u00e9l\u00e9coms, Communication &amp; M\u00e9dia\u2019<\/strong> qui rapportent la Pr\u00e9vision Nette d\u2019Emploi \u00a0la plus forte <strong>(+53%)<\/strong>, confirmant la forte demande de profils digitaux pour soutenir la transformation des entreprises et de l\u2019\u00e9conomie en g\u00e9n\u00e9ral. Plus de six employeurs sur dix sond\u00e9s dans ce secteur pr\u00e9voient de renforcer ses effectifs d\u2019ici la fin du mois de mars 2022. Les pr\u00e9visions sont \u00e9galement tr\u00e8s optimistes dans le secteur de la <strong>Construction (+48%)<\/strong>, ainsi que dans le secteur de la <strong>Finance, des banques, de l\u2019assurance et de l\u2019immobilier (+45%)<\/strong>. Les employeurs sond\u00e9s rapportent des Pr\u00e9visions Nette d\u2019Emploi tr\u00e8s encourageantes dans les secteurs du <strong>Commerce de gros et de d\u00e9tail \/\u00a0 Supply Chain &amp; Logistique (+41%)<\/strong> ainsi que dans l\u2019<strong>Industrie manufacturi\u00e8re (+38%).<\/strong> Enfin l\u2019activit\u00e9 de recrutement devrait \u00eatre plus mod\u00e9r\u00e9e dans le secteur des Autres services (+29%),\u00a0 des Services publics, de la sant\u00e9, de l\u2019\u00e9ducation et des services collectifs (+27%), dans l\u2019Horeca \/ Culture &amp; Loisirs (+22%), ainsi que dans le secteur Production Primaire (+20%) \u2013 Agriculture et p\u00eache, \u00c9lectricit\u00e9 Gaz et eau, Industries extractives \u2013 et autres Industries (+15%).<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7438 size-full\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR.png\" alt=\"\" width=\"2401\" height=\"1255\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR.png 2401w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR-300x157.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR-1024x535.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR-768x401.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR-1536x803.png 1536w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR-2048x1070.png 2048w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR-260x136.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR-50x26.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/07_NEO_Outlook_-sectors_-MEOS_Q122_-BEFR-143x75.png 143w\" sizes=\"(max-width: 2401px) 100vw, 2401px\" \/><\/a><\/p>\n<h2><strong>La confiance des employeurs s\u2019accro\u00eet avec la taille des entreprises<\/strong><\/h2>\n<p>Selon l\u2019enqu\u00eate de ManpowerGroup, la Pr\u00e9vision Nette d\u2019Emploi affiche une valeur en progression en fonction de la taille de l\u2019entreprise\u00a0: <strong>+\u00a015%<\/strong> pour les <strong>micro-entreprises<\/strong> (&lt; 10 travailleurs), <strong>+23%<\/strong> pour les <strong>petites entreprises<\/strong> (10-49 travailleurs), <strong>+35%<\/strong> pour les <strong>moyennes entreprises<\/strong> (50-249 travailleurs) et <strong>+46%<\/strong> dans les <strong>grandes entreprises<\/strong> (\u2265 250 travailleurs).<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7441 size-full\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR.png\" alt=\"\" width=\"2401\" height=\"1255\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR.png 2401w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR-300x157.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR-1024x535.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR-768x401.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR-1536x803.png 1536w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR-2048x1070.png 2048w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR-260x136.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR-50x26.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/08_NEO_Outlook_-company_size_-MEOS_Q122_-BEFR-143x75.png 143w\" sizes=\"(max-width: 2401px) 100vw, 2401px\" \/><\/a><\/p>\n<h2><\/h2>\n<h2><strong>Perspectives d\u2019emploi positives dans tous les 40 pays et territoires sond\u00e9s \u00a0<\/strong><\/h2>\n<p>Pour la premi\u00e8re fois depuis avant le d\u00e9but de la pand\u00e9mie, les perspectives d\u2019emploi sont positives dans les 40 pays et territoires sond\u00e9s, et en progression dans 36 d\u2019entre eux en comparaison trimestrielle. <strong>La Pr\u00e9vision Nette d\u2019Emploi s\u2019\u00e9l\u00e8ve \u00e0 +37% au niveau mondial.<\/strong><\/p>\n<p>Cette tendance encourageante est \u00e9galement observ\u00e9e dans la r\u00e9gion EMEA (Europe, Moyen-Orient, Afrique), avec des intentions de recrutement positives dans les 23 pays sond\u00e9s, en progression dans 22 d\u2019entre eux en comparaison trimestrielle. C\u2019est aux <strong>Pays-Bas (+47%)<\/strong>, en Irlande (+47%), au Portugal (+37%), en <strong>Allemagne (+36%)<\/strong>\u00a0et Autriche (+36%) que l\u2019on trouve les Pr\u00e9visions Nettes d\u2019Emploi les plus optimistes en Europe. Avec +34%, <strong>la Pr\u00e9vision Nette d\u2019Emploi de la Belgique se situe au-dessus de la moyenne de la r\u00e9gion EMEA (+28%)<\/strong> et devant le <strong>Royaume-Uni (+32%)<\/strong>, l\u2019Italie (+28%) ou la <strong>France (+26%)<\/strong>. C\u2019est en Hongrie (+19%), en Gr\u00e8ce (+16% et en R\u00e9publique Tch\u00e8que (+14%) que l\u2019on observe les pr\u00e9visions les plus faibles de la r\u00e9gion.<\/p>\n<p>Les perspectives d\u2019emploi sont \u00e9galement tr\u00e8s optimistes en Inde (+49%), au Br\u00e9sil (+47%) et aux Etats-Unis (+41%), tandis qu\u2019elles sont plus mod\u00e9r\u00e9es en <strong>Chine (+25%)<\/strong>. Enfin c\u2019est \u00e0 Taiwan (+13%) et au <strong>Japon (+11%)<\/strong> que les employeurs rapportent les intentions de recrutement les plus faibles de tous les pays et territoires sond\u00e9s au niveau mondial.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7444 size-full\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR.png\" alt=\"\" width=\"2401\" height=\"1255\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR.png 2401w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR-300x157.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR-1024x535.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR-768x401.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR-1536x803.png 1536w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR-2048x1070.png 2048w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR-260x136.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR-50x26.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/09_NEO_Outlook_-countries_-MEOS_Q122_-BEFR-143x75.png 143w\" sizes=\"(max-width: 2401px) 100vw, 2401px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong><em>Les r\u00e9sultats de la prochaine \u00e9dition du Barom\u00e8tre ManpowerGroup des perspectives d\u2019Emploi seront diffus\u00e9s\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 le 8 mars 2022 (2\u00e8me trimestre 2022).<\/em><\/strong><\/p>\n<p>(1) <strong>L\u2019enqu\u00eate de ManpowerGroup a \u00e9t\u00e9 men\u00e9e en octobre 2021<\/strong>, soit avant les nouvelles restrictions impos\u00e9es en raison de la quatri\u00e8me vague du coronavirus<\/p>\n<p><em>(2) <\/em>La valeur de la <strong>Pr\u00e9vision Nette d&rsquo;Emploi<\/strong> est obtenue en d\u00e9duisant du pourcentage des employeurs anticipant une hausse de l&#8217;emploi total, le pourcentage des employeurs pr\u00e9voyant une baisse de l&#8217;emploi dans leur entreprise pour le trimestre suivant. Il s&rsquo;agit donc ici du solde net des pr\u00e9visions d&#8217;emploi, qui peut \u00eatre aussi bien positif que n\u00e9gatif. Les commentaires se basent sur les donn\u00e9es d\u00e9saisonnalis\u00e9es, lorsqu\u2019elles sont disponibles. Les donn\u00e9es corrig\u00e9es des variations saisonni\u00e8res ne sont pas disponibles pour la Croatie.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/BE_FR_MEOSReport_1Q22.pdf\" target=\"_blank\" rel=\"noopener\"><strong>T\u00e9l\u00e9chargez le Rapport<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/BE_FR_MEOSReport_1Q22.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7447 size-full\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR.png\" alt=\"\" width=\"2401\" height=\"1255\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR.png 2401w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR-300x157.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR-1024x535.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR-768x401.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR-1536x803.png 1536w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR-2048x1070.png 2048w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR-260x136.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR-50x26.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2021\/12\/Download_Q122_BEFR-143x75.png 143w\" sizes=\"(max-width: 2401px) 100vw, 2401px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e8s d\u2019un employeur sur deux (48%) pr\u00e9voit des embauches au 1er trimestre 2022, selon le Barom\u00e8tre de l\u2019emploi de ManpowerGroup &nbsp; Selon le Barom\u00e8tre de ManpowerGroup<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":4,"featured_media":7548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[24],"tags":[122,37,151,317,38],"class_list":["post-7409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-barometre-manpowergroup","tag-emploi","tag-intentions-de-recrutement","tag-job-2","tag-manpowergroup"],"_links":{"self":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/7409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/comments?post=7409"}],"version-history":[{"count":8,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/7409\/revisions"}],"predecessor-version":[{"id":7531,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/7409\/revisions\/7531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/media\/7548"}],"wp:attachment":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/media?parent=7409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/categories?post=7409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/tags?post=7409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}