{"id":542,"date":"2017-03-14T10:52:36","date_gmt":"2017-03-14T09:52:36","guid":{"rendered":"http:\/\/blog.manpowergroup.be\/?p=542"},"modified":"2017-04-06T16:05:49","modified_gmt":"2017-04-06T14:05:49","slug":"93-des-employeurs-belges-prevoient-de-maintenir-leurs-effectifs-au-meme-niveau-au-cours-du-prochain-trimestre","status":"publish","type":"post","link":"https:\/\/manpowergroup.be\/fr\/2017\/03\/14\/93-des-employeurs-belges-prevoient-de-maintenir-leurs-effectifs-au-meme-niveau-au-cours-du-prochain-trimestre\/","title":{"rendered":"93% des employeurs belges pr\u00e9voient de maintenir leurs effectifs au m\u00eame niveau au cours du prochain trimestre"},"content":{"rendered":"<h2>Barom\u00e8tre de l\u2019emploi de ManpowerGroup \u2013 Q2\/2017<\/h2>\n<p>Selon le Barom\u00e8tre Manpower publi\u00e9 ce jour, les employeurs belges rapportent des intentions de recrutement prudentes pour le 2e trimestre 2017. Au niveau national, seulement 4% des 751 employeurs belges interrog\u00e9s fin janvier par ManpowerGroup pr\u00e9voient d\u2019augmenter leurs effectifs d\u2019ici la fin du juin 2017, tandis que 3% planifient de les r\u00e9duire. 93% des employeurs sond\u00e9s ne pr\u00e9voient aucun changement dans leur masse salariale. Apr\u00e8s correction des variations saisonni\u00e8res, la Pr\u00e9vision Nette d\u2019Emploi \u2013 ou le diff\u00e9rentiel entre le pourcentage d\u2019employeurs pr\u00e9voyant des embauches et le pourcentage de ceux pr\u00e9voyant des licenciements \u2013 atteint la valeur de 0, indiquant une activit\u00e9 de recrutement en repli par rapport aux trois premiers mois de l\u2019ann\u00e9e. C\u2019est une diminution importante de 6 points par rapport au trimestre pr\u00e9c\u00e9dent et baisse de 1 point par rapport \u00e0 la m\u00eame p\u00e9riode l\u2019an dernier.<\/p>\n<ul>\n<li>L\u2019optimisme observ\u00e9 lors du trimestre pr\u00e9c\u00e9dent s\u2019est quelque peu estomp\u00e9 et les employeurs belges rapportent une Pr\u00e9vision Nette d\u2019Emploi en recul de 6 points pour se fixer \u00e0 un niveau 0, indiquant une activit\u00e9 de recrutement assez limit\u00e9e.<\/li>\n<li>Le climat d\u2019embauche devrait \u00eatre l\u00e9g\u00e8rement positif en Flandre (+2), incertain \u00e0 Bruxelles (0), et l\u00e9g\u00e8rement n\u00e9gatif en Wallonie (-2).<\/li>\n<li>Les perspectives d\u2019emploi sont positives dans six des 10 secteurs sond\u00e9s, mais en recul dans huit d\u2019entre eux par rapport au trimestre pr\u00e9c\u00e9dent.<\/li>\n<li>Les employeurs des grandes (+28) et des moyennes (+17) entreprises rapportent les intentions de recrutement les plus fortes.<\/li>\n<li>Dans la r\u00e9gion EMEA, les pr\u00e9visions de recrutement sont positives dans 22 des 25 pays sond\u00e9s. Le march\u00e9 de l\u2019emploi devrait \u00eatre particuli\u00e8rement dynamique dans les pays de l\u2019Europe de l\u2019Est.<\/li>\n<li>A l\u2019\u00e9chelle mondiale, les perspectives d\u2019embauche devraient s\u2019inscrire dans la continuit\u00e9 de celles observ\u00e9es lors des trois premiers mois de l\u2019ann\u00e9e, avec un Pr\u00e9vision Nette d\u2019Emploi positive dans 39 des 43 pays et territoires sond\u00e9s.<\/li>\n<\/ul>\n<h3>O\u00f9 sont les jobs ?<\/h3>\n<p><a href=\"http:\/\/blog.manpowergroup.be\/wp-content\/uploads\/2017\/03\/MAN-5967-infographic-meos-FR-DEF-HI.jpg\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-554 size-large\" src=\"http:\/\/blog.manpowergroup.be\/wp-content\/uploads\/2017\/03\/MAN-5967-infographic-meos-FR-DEF-HI-500x1024.jpg\" alt=\"\" width=\"500\" height=\"1024\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2017\/03\/MAN-5967-infographic-meos-FR-DEF-HI-500x1024.jpg 500w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2017\/03\/MAN-5967-infographic-meos-FR-DEF-HI-146x300.jpg 146w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2017\/03\/MAN-5967-infographic-meos-FR-DEF-HI-768x1573.jpg 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2017\/03\/MAN-5967-infographic-meos-FR-DEF-HI-71x146.jpg 71w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2017\/03\/MAN-5967-infographic-meos-FR-DEF-HI-24x50.jpg 24w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2017\/03\/MAN-5967-infographic-meos-FR-DEF-HI-37x75.jpg 37w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barom\u00e8tre de l\u2019emploi de ManpowerGroup \u2013 Q2\/2017 Selon le Barom\u00e8tre Manpower publi\u00e9 ce jour, les employeurs belges rapportent des intentions de recrutement prudentes pour le 2e<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":4,"featured_media":546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[24],"tags":[36,37,38,39],"class_list":["post-542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-barometre","tag-emploi","tag-manpowergroup","tag-recrutement"],"_links":{"self":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/comments?post=542"}],"version-history":[{"count":6,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/542\/revisions"}],"predecessor-version":[{"id":767,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/542\/revisions\/767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/media\/546"}],"wp:attachment":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/media?parent=542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/categories?post=542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/tags?post=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}