{"id":2435,"date":"2019-02-26T09:38:12","date_gmt":"2019-02-26T08:38:12","guid":{"rendered":"https:\/\/manpowergroup.be\/?p=2435"},"modified":"2019-06-19T17:11:31","modified_gmt":"2019-06-19T15:11:31","slug":"robots-recherchent-humains-quand-les-machines-ne-peuvent-se-passer-de-lhomme","status":"publish","type":"post","link":"https:\/\/manpowergroup.be\/fr\/2019\/02\/26\/robots-recherchent-humains-quand-les-machines-ne-peuvent-se-passer-de-lhomme\/","title":{"rendered":"Les employeurs pr\u00e9voient d\u2019augmenter  ou de maintenir leurs effectifs sous l\u2019effet de la digitalisation"},"content":{"rendered":"<p><strong>Les robots vont-ils voler les emplois de l\u2019Homme ? C\u2019est la question qui est sur toutes les l\u00e8vres depuis une dizaine d\u2019ann\u00e9es. En pratique, c\u2019est tout le contraire qui semble vou\u00e9 \u00e0 se produire, comme le montre la troisi\u00e8me \u00e9dition de l\u2019\u00e9tude men\u00e9e par ManpowerGroup sur l\u2019impact de la digitalisation sur l\u2019emploi. En effet, les employeurs n\u2019ont jamais \u00e9t\u00e9 si nombreux (93% contre 91% l\u2019an dernier) \u00e0 pr\u00e9voir d\u2019accro\u00eetre leurs effectifs ou de les maintenir au niveau actuel en raison de l\u2019automatisation de certaines t\u00e2ches. Aujourd\u2019hui, la priorit\u00e9 sur le march\u00e9 du travail consiste \u00e0 accompagner l\u2019impact de la transformation digitale sur les comp\u00e9tences.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>L\u2019automatisation est cr\u00e9atrice d\u2019emploi \u00a0<\/strong><\/h2>\n<p>Pour son enqu\u00eate, ManpowerGroup a interrog\u00e9 19.000 employeurs dans 44 pays.\u00a0 En Belgique, comme ailleurs dans le monde, les employeurs dressent pour la troisi\u00e8me ann\u00e9e cons\u00e9cutive le m\u00eame constat.\u00a0 <strong>La digitalisation n\u2019est pas synonyme de destruction d\u2019emploi. 15% des employeurs belges pr\u00e9voient d\u2019augmenter leurs effectifs en raison de la digitalisation, alors que seulement 5% d\u2019entre eux pr\u00e9voient de les r\u00e9duire. <\/strong>93% des employeurs belges interrog\u00e9s (87% au niveau mondial) pr\u00e9voient de maintenir ou de renforcer leurs effectifs en raison de l\u2018automatisation, c\u2019est un chiffre relativement stable par rapport \u00e0 l\u2019an dernier (91%).\u00a0 Dans seulement 6 pays (principalement en Europe de l\u2019Est), on trouve davantage de pessimisme face \u00e0 l\u2019int\u00e9gration des robots sur les lieux de travail, alors que deux tiers des employeurs sond\u00e9s dans la r\u00e9gion EMEA (Europe, Moyen Orient, Afrique) estiment que la digitalisation n\u2019aura pas d\u2019influence sur la taille de leurs effectifs end\u00e9ans les deux ans.<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/ManpowerGroup-impact_-digitalisation_-2019.png\" target=\"_blank\" rel=\"noopener noreferrer\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2438 size-large\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/ManpowerGroup-impact_-digitalisation_-2019-1024x512.png\" alt=\"\" width=\"1024\" height=\"512\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/ManpowerGroup-impact_-digitalisation_-2019-1024x512.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/ManpowerGroup-impact_-digitalisation_-2019-300x150.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/ManpowerGroup-impact_-digitalisation_-2019-768x384.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/ManpowerGroup-impact_-digitalisation_-2019-260x130.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/ManpowerGroup-impact_-digitalisation_-2019-50x25.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/ManpowerGroup-impact_-digitalisation_-2019-150x75.png 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<h2><\/h2>\n<h2><strong>\u00a0Des emplois pris\u00e9s et des emplois menac\u00e9s <\/strong><\/h2>\n<p>F<strong>ace \u00e0 l\u2019essor de l\u2019automatisation, la nature des comp\u00e9tences dont les entreprises ont besoin est en train de changer, \u00e0 un rythme qui varie toutefois consid\u00e9rablement selon les m\u00e9tiers.<\/strong> Comme l\u2019an dernier, l<strong>es profils IT s\u2019imposent sans surprise comme les grands gagnants de la digitalisation avec une demande d\u2019expertise qui progresse \u00e0 vive allure<\/strong>\u00a0: 16\u00a0% des entreprises belges entendent recruter des sp\u00e9cialistes de l\u2019informatique, soient trois fois plus que celles qui envisagent des r\u00e9ductions d\u2019effectifs dans ce domaine. Pendant ce temps, les experts en technologie se rar\u00e9fient et un \u00e9cart se creuse entre les niveaux de formation et l\u2019exp\u00e9rience que les employeurs exigent de la part des candidats et la r\u00e9alit\u00e9 du march\u00e9, qu\u2019il s\u2019agisse des d\u00e9veloppeurs, des sp\u00e9cialistes infrastructure ou des profils experts en s\u00e9curit\u00e9. On attend \u00e9galement une f<strong>orte croissance des postes en prise directe avec la client\u00e8le<\/strong> (solde net \u00e0 +8%), notamment en raison du d\u00e9veloppement de l\u2019e-commerce et la virtualisation des contacts commerciaux. Une entreprise belge sond\u00e9e sur dix pr\u00e9voit de cr\u00e9er des emplois pour am\u00e9liorer l\u2019exp\u00e9rience de ses clients. L\u2019<strong>Industrie manufacturi\u00e8re<\/strong> anticipe aussi des changements\u00a0: 9\u00a0% des employeurs annoncent qu\u2019ils emploieront davantage de salari\u00e9s \u00e0 court terme, tandis que 6\u00a0% pr\u00e9voient de r\u00e9duire leur masse salariale\u00a0: une balance de l\u2019emploi exc\u00e9dentaire ponctu\u00e9e d\u2019une v\u00e9ritable r\u00e9volution des comp\u00e9tences dans le secteur.<\/p>\n<p>\u00c0 l\u2019inverse, les <strong>m\u00e9tiers administratifs<\/strong> sont en perte de vitesse (solde net \u00e0 -15%)\u00a0:\u00a0 pr\u00e8s d\u2019un employeur belge sur cinq pr\u00e9voit de d\u00e9truire des emplois en ce domaine au cours des deux prochaines ann\u00e9es. L\u2019automatisation devrait continuer \u00e0 engendrer des r\u00e9ductions d\u2019emplois dans les <strong>m\u00e9tiers de la comptabilit\u00e9 et de la finance<\/strong> (solde \u00e0 -11%) tandis que l\u2019emploi devrait rester stable dans le secteur des ressources humaines (solde \u00e0 0%).<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Impact_Digitalisation_fonctions_-ManpowerGroup_2019-1.png\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"aligncenter wp-image-2763 size-large\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Impact_Digitalisation_fonctions_-ManpowerGroup_2019-1-1024x512.png\" alt=\"\" width=\"1024\" height=\"512\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Impact_Digitalisation_fonctions_-ManpowerGroup_2019-1-1024x512.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Impact_Digitalisation_fonctions_-ManpowerGroup_2019-1-300x150.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Impact_Digitalisation_fonctions_-ManpowerGroup_2019-1-768x384.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Impact_Digitalisation_fonctions_-ManpowerGroup_2019-1-260x130.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Impact_Digitalisation_fonctions_-ManpowerGroup_2019-1-50x25.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Impact_Digitalisation_fonctions_-ManpowerGroup_2019-1-150x75.png 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><strong>Les robots ont besoin des humains<\/strong><\/p>\n<p><em>\u00ab <strong>Se demander en permanence si les robots vont prendre nos emplois nous \u00e9loigne du v\u00e9ritable d\u00e9bat<\/strong> \u00bb<\/em> affirme Philippe Lacroix, Managing Director de ManpowerGroup BeLux. <em>\u00ab\u2009Certes, de plus en plus de machines viennent grossir les rangs des entreprises, mais cela n\u2019emp\u00eache pas celles-ci de continuer \u00e0 cr\u00e9er des emplois. <strong>Le march\u00e9 du travail se transforme profond\u00e9ment et les entreprises doivent se donner les moyens de renforcer les comp\u00e9tences de leurs employ\u00e9s pour les pr\u00e9parer \u00e0 des m\u00e9tiers \u00e9mergents et compl\u00e9mentaires \u00e0 ceux qui seront tenus par des machines.<\/strong> Oui, les robots ont besoin des humains\u2026 encore faut-il que ces derniers disposent des comp\u00e9tences n\u00e9cessaires n\u00e9cessaires pour faire \u00e9quipe avec eux.\u00a0\u00bb<\/em><\/p>\n<p><em> <img decoding=\"async\" class=\"alignnone size-full wp-image-2437\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/thumbnail-robots.jpg\" alt=\"\" width=\"1500\" height=\"500\" \/><\/em><\/p>\n<h2><strong>Priorit\u00e9s aux qualit\u00e9s humaines\u2026 m\u00eame si les comp\u00e9tences techniques sont un passeport indispensable \u00e0 l\u2019emploi<\/strong><\/h2>\n<p>Les comp\u00e9tences d\u2019ordre technologique et num\u00e9rique sont de plus en plus recherch\u00e9es dans tous les m\u00e9tiers, mais ce sont bien les qualit\u00e9s humaines que les employeurs valorisent plus qu\u2019hier, \u00e0 l\u2019heure o\u00f9 l\u2019automatisation devient la norme et les machines gagnent en efficacit\u00e9 dans l\u2019ex\u00e9cution de t\u00e2ches routini\u00e8res. <strong>Et si 39\u00a0% des entreprises belges peinent \u00e0 former leurs salari\u00e9s aux comp\u00e9tences techniques les plus demand\u00e9es, 45\u00a0% rencontrent encore plus de difficult\u00e9s \u00e0 leur faire acqu\u00e9rir les qualit\u00e9s humaines dont elles ont besoin,<\/strong> comme le sens de l\u2019analyse et la communication. Aujourd\u2019hui, l\u2019avenir appartient aux candidats qui font montre de comp\u00e9tences cognitives sup\u00e9rieures \u00e0 la moyenne, de cr\u00e9ativit\u00e9, d\u2019aptitudes \u00e0 assimiler et exploiter des informations complexes, tout en \u00e9tant \u00e0 la fois adaptables et agr\u00e9ables \u00e0 vivre. Selon le Forum \u00e9conomique mondial, d\u2019ici 2030, la demande de qualit\u00e9s humaines tant sociales qu\u2019\u00e9motionnelles va progresser, tous secteurs confondus, de 26\u00a0% aux \u00c9tats-Unis et de 22\u00a0% en Europe.<\/p>\n<p><em>\u00ab\u00a0Toutes les \u00e9tudes mettent en \u00e9vidence l\u2019importance des soft skills, il n\u2019en demeure pas moins vrai que les comp\u00e9tences techniques sont un passeport indispensable pour acc\u00e9der \u00e0 un emploi<\/em> \u00bb pr\u00e9cise Philippe Lacroix.<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Capture-leanability.png\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2441 size-full\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Capture-leanability.png\" alt=\"\" width=\"798\" height=\"230\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Capture-leanability.png 798w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Capture-leanability-300x86.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Capture-leanability-768x221.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Capture-leanability-260x75.png 260w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Capture-leanability-50x14.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/Capture-leanability-150x43.png 150w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>7 suggestions pour faire coexister l\u2019homme et la machine<\/strong><\/h2>\n<p>Alors que digitalisation et automatisation deviennent la norme en entreprise, les politiques de gestion RH doivent \u00e9voluer. Les <strong>difficult\u00e9s de recrutement<\/strong> atteignant un niveau record partout dans le monde et les employeurs pr\u00e9voyant d\u2019automatiser certaines t\u00e2ches et de cr\u00e9er de l\u2019emploi, on ne peut plus se contenter de d\u00e9nicher des talents\u00a0: il faut les fa\u00e7onner. Dans son <a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/MANPOWERGROUP_WEF_SkillsRevolution_4.0_paper.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">rapport<\/a> <strong>\u2018Humans wanted\u00a0: The Robots need you\u2019,<\/strong> ManpowerGroup formulent 7 recommandations pour faire coexister l\u2019homme et la machine. Avec en fil rouge, la formation continue et le d\u00e9veloppement des comp\u00e9tences. En effet, <strong>plus de 9 employeurs belges sur 10 ont d\u00e9clar\u00e9 vouloir renforcer les comp\u00e9tences de leur personnel d\u2019ici 2020 afin de faire face au d\u00e9fi de la digitalisation.<\/strong><\/p>\n<h2>\u00c0 propos de l\u2019\u00e9tude<\/h2>\n<p>ManpowerGroup a demand\u00e9 \u00e0 Infocorp une \u00e9tude quantitative en octobre 2018 aupr\u00e8s de 19 417 employeurs au sein de 6 secteurs dans 44 pays, dont la Belgique.<\/p>\n<p>L\u2019analyse des donn\u00e9es a \u00e9t\u00e9 effectu\u00e9e par Reputation Leaders. Nous avons demand\u00e9 leur avis sur :<br \/>\n* l\u2019impact probable de l\u2019automatisation sur leurs effectifs dans les deux prochaines ann\u00e9es<br \/>\n* les fonctions les plus touch\u00e9es au sein de leur organisation<br \/>\n* les strat\u00e9gies de gestion des talents \u00e0 mettre en \u0153uvre<\/p>\n<p>T\u00e9l\u00e9chargez gratuitement notre <a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/MANPOWERGROUP_WEF_SkillsRevolution_4.0_paper.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">white paper<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2443 alignleft\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/COVER-WHITE-PAPER-230x300.png\" alt=\"\" width=\"230\" height=\"300\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/COVER-WHITE-PAPER-230x300.png 230w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/COVER-WHITE-PAPER-112x146.png 112w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/COVER-WHITE-PAPER-38x50.png 38w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/COVER-WHITE-PAPER-58x75.png 58w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2019\/02\/COVER-WHITE-PAPER.png 639w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les robots vont-ils voler les emplois de l\u2019Homme ? C\u2019est la question qui est sur toutes les l\u00e8vres depuis une dizaine d\u2019ann\u00e9es. En pratique, c\u2019est tout<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":3,"featured_media":2461,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[24],"tags":[],"class_list":["post-2435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/2435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/comments?post=2435"}],"version-history":[{"count":11,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/2435\/revisions"}],"predecessor-version":[{"id":2764,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/2435\/revisions\/2764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/media\/2461"}],"wp:attachment":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/media?parent=2435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/categories?post=2435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/tags?post=2435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}