{"id":14309,"date":"2025-06-09T22:14:51","date_gmt":"2025-06-09T20:14:51","guid":{"rendered":"https:\/\/manpowergroup.be\/?p=14309"},"modified":"2025-06-09T22:14:51","modified_gmt":"2025-06-09T20:14:51","slug":"intentions-de-recrutement-en-recul-dans-un-contexte-economique-hyper-volatile-barometre-de-lemploi-de-manpowergroup-q3-2025","status":"publish","type":"post","link":"https:\/\/manpowergroup.be\/fr\/2025\/06\/09\/intentions-de-recrutement-en-recul-dans-un-contexte-economique-hyper-volatile-barometre-de-lemploi-de-manpowergroup-q3-2025\/","title":{"rendered":"Intentions de recrutement en recul dans un contexte \u00e9conomique hyper volatile (Barom\u00e8tre de l&#8217;emploi de ManpowerGroup Q3\/2025)"},"content":{"rendered":"<h3 style=\"text-align: center;\"><em>La Pr\u00e9vision Nette d\u2019Emploi pour le 3e trimestre 2025 chute \u00e0 +20% \u2013 son niveau le plus bas depuis deux ans \u2013 , tandis que l\u2019incertitude li\u00e9e au commerce mondial influence les d\u00e9cisions d\u2019embauche de 6 entreprises sur 10 sond\u00e9es en Belgique.<\/em><\/h3>\n<p>&nbsp;<\/p>\n<p>Selon le Barom\u00e8tre de l\u2019emploi de ManpowerGroup publi\u00e9 ce jour, <strong>les employeurs \u00a0belges anticipent un nouveau ralentissement des embauches au cours du 3<sup>e<\/sup> trimestre 2025.<\/strong> \u00a0En effet, sur les 525 employeurs sond\u00e9s en avril par ManpowerGroup, 39% pr\u00e9voient d\u2019augmenter leurs effectifs d\u2019ici la fin du mois de septembre 2025, tandis que 19% d\u2019entre eux pr\u00e9voient de les r\u00e9duire. 41% des employeurs interrog\u00e9s n\u2019anticipent aucun changement.<\/p>\n<p>Apr\u00e8s correction des variations saisonni\u00e8res, <strong>la Pr\u00e9vision Nette d\u2019Emploi<\/strong><sup><strong>(1)<\/strong> <\/sup>\u2013 ou le diff\u00e9rentiel entre le pourcentage d\u2019employeurs pr\u00e9voyant des\u00a0 embauches et le pourcentage de ceux pr\u00e9voyant des r\u00e9ductions d\u2019effectifs \u2013 \u00a0<strong>atteint +20%, en recul pour le deuxi\u00e8me trimestre cons\u00e9cutif et \u00e0 \u00a0son niveau le plus bas depuis le \u00a02e trimestre 2023.<\/strong> C\u2019est une baisse de 4 points par rapport au trimestre pr\u00e9c\u00e9dent et de 5 points par rapport au 3e trimestre 2024. Avec ce chiffre, la Belgique se situe 1 point au-dessus de la moyenne observ\u00e9e dans la r\u00e9gion EMEA (Europe, Moyen-Orient, Afrique) (+19%) et 4 points en-dessous de la moyenne mondiale (+24%).<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-14311 size-large\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-1024x1024.png\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-1024x1024.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-300x300.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-150x150.png 150w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-768x768.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-146x146.png 146w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-50x50.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-75x75.png 75w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-85x85.png 85w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR-80x80.png 80w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/4_Outlook_-Belgium_Q325_-BEFR.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00ab <strong>L\u2019analyse des r\u00e9sultats de notre enqu\u00eate montre que, dans un contexte \u00e9conomique hyper volatile, les employeurs belges pr\u00e9voient de ralentir leurs embauches au cours du prochain trimestre : 6 sur 10 d\u00e9clarent que l\u2019incertitude li\u00e9e au commerce international influence directement leurs d\u00e9cisions en mati\u00e8re de recrutement \u00bb<\/strong>,<\/em> explique S\u00e9bastien Delfosse, Managing Director de ManpowerGroup BeLux. <em>\u00ab Dans le m\u00eame temps, ls employeurs sont confront\u00e9s \u00e0 des bouleversements sans pr\u00e9c\u00e9dent sur le march\u00e9 du travail \u2013 \u00e9volution d\u00e9mographique, avanc\u00e9es technologiques rapides et pressions \u00e9conomiques \u2013 qui les obligent \u00e0 repenser leurs strat\u00e9gies, en investissant davantage dans l\u2019automatisation tout en g\u00e9rant plus prudemment leurs besoins en talents. \u00bb<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>En effet, selon les chiffres de ManpowerGroup, le d\u00e9part massif des travailleurs \u00e2g\u00e9s du march\u00e9 du travail impacte directement la strat\u00e9gie RH de plus d\u2019un employeur sur deux (54 %), \u00a0\u2013 un ph\u00e9nom\u00e8ne particuli\u00e8rement marqu\u00e9 \u00e0 Bruxelles (62%), en Flandre (58%) et en Wallonie (47%). Parall\u00e8lement, 54% des entreprises belges d\u00e9clarent vouloir augmenter leurs investissements en mati\u00e8re d\u2019automatisation au cours des 12 prochains mois, alors que la pression sur l\u2019emploi s\u2019intensifie en m\u00eame temps que l\u2019acc\u00e9l\u00e9ration des transformations technologiques, notamment li\u00e9es \u00e0 l\u2019intelligence artificielle.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-14314 size-large\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-1024x1024.png\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-1024x1024.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-300x300.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-150x150.png 150w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-768x768.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-146x146.png 146w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-50x50.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-75x75.png 75w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-85x85.png 85w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR-80x80.png 80w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/13_Trade_Uncertainty_Q325-BEFR.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Dynamique contrast\u00e9e entre les r\u00e9gions<\/strong><\/h2>\n<p><strong>Les employeurs rapportent des intentions de recrutement positives dans les trois r\u00e9gions du pays : +31% \u00e0 Bruxelles, +22% en Wallonie et +17% en Flandre.<\/strong> La Pr\u00e9vision Nette d\u2019Emploi enregistre une hausse de 9 points \u00e0 Bruxelles par rapport au trimestre pr\u00e9c\u00e9dent, tandis qu\u2019elle reste stable en Wallonie. En revanche, en Flandre, les pr\u00e9visions sont en net recul : diminution de\u00a0 11 points sur une base trimestrielle et 14 points sur une base annuelle.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-14317 size-large\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-1024x1024.png\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-1024x1024.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-300x300.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-150x150.png 150w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-768x768.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-146x146.png 146w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-50x50.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-75x75.png 75w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-85x85.png 85w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR-80x80.png 80w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/6_Regions_-Outlook_-Belgium_Q325_-BEFR.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>Croissance des recrutements dans le secteur IT<\/strong><\/h2>\n<p>Les employeurs de 8 des 9 secteurs d\u2019activit\u00e9 sond\u00e9s en Belgique pr\u00e9voient d\u2019augmenter leurs effectifs d\u2019ici la fin du mois de septembre 2025. Comme au trimestre pr\u00e9c\u00e9dent, les tendances varient fortement selon les secteurs. \u00a0<strong>L\u2019activit\u00e9 de recrutement devrait \u00eatre particuli\u00e8rement dynamique dans le secteur des technologies de l\u2019information (IT), avec une Pr\u00e9vision Nette d\u2019Emploi \u00e0 +52% :<\/strong> plus de 6 employeurs sur 10 interrog\u00e9s pr\u00e9voient d\u2019augmenter leurs effectifs au cours du\u00a0 prochain trimestre.<\/p>\n<p>Des pr\u00e9visions \u00e9galement favorables sont observ\u00e9es dans les secteurs des Activit\u00e9s financi\u00e8res et de l\u2019Immobilier (+37%) ainsi que dans celui des Biens de consommation, Services, Horeca et Retail (+27%). \u00c0 l\u2019inverse, les opportunit\u00e9s d\u2019emploi s\u2019annoncent plus limit\u00e9es dans l\u2019Industrie manufacturi\u00e8re et la Construction (+19%), les Soins de sant\u00e9 et Sciences de la vie (+15%), les Services publics, l\u2019\u00e9ducation et autres services (+11%), ainsi que dans le Transport, la Logistique et l\u2019Automobile (+6%). Enfin, seul le secteur des Services de communication affiche une Pr\u00e9vision Nette d\u2019Emploi n\u00e9gative, \u00e0 -4%.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14323 size-large\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-1024x1024.png\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-1024x1024.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-300x300.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-150x150.png 150w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-768x768.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-146x146.png 146w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-50x50.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-75x75.png 75w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-85x85.png 85w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR-80x80.png 80w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/7_Sectors_-Outlook_-Belgium_Q325_-BEFR.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Perspectives d\u2019emploi positives les 42 pays sond\u00e9s au niveau\u00a0 mondial<\/strong><\/h2>\n<p>L\u2019analyse des r\u00e9sultats de l\u2019enqu\u00eate men\u00e9e par ManpowerGroup aupr\u00e8s de plus de 40.000 employeurs r\u00e9v\u00e8le des perspectives d\u2019emploi positives dans les 42 pays sond\u00e9s. <strong>La Pr\u00e9vision Nette d\u2019Emploi s\u2019\u00e9tablit \u00e0 +24%, un niveau relativement stable pour le quatri\u00e8me trimestre cons\u00e9cutif.<\/strong> Les employeurs des \u00c9mirats Arabes Unis (+48%) et de l\u2019Inde (+42%) se montrent les plus optimistes, tandis que ceux d\u2019Argentine (+3%) affichent les pr\u00e9visions les plus prudentes.<\/p>\n<p><strong>La situation est plus contrast\u00e9e dans la r\u00e9gion EMEA, o\u00f9 la Pr\u00e9vision Nette d\u2019Emploi atteint +19%<\/strong>, en baisse d\u2019un point par rapport au trimestre pr\u00e9c\u00e9dent et stable par rapport \u00e0 la m\u00eame p\u00e9riode l\u2019an dernier. Les intentions de recrutement reculent dans 14 pays sur 23 en comparaison trimestrielle, et dans 13 pays sur une base annuelle.<\/p>\n<p><strong>Avec une Pr\u00e9vision Nette d\u2019Emploi \u00e0 +20%, la Belgique se classe dans la moyenne sup\u00e9rieure des pays sond\u00e9s en Europe,<\/strong> au m\u00eame niveau que l\u2019Allemagne (+20%). Elle se situe cependant derri\u00e8re les Pays-Bas (+30%), l\u2019Irlande (+29%), la Su\u00e8de (+24%) et la Suisse (+24%), mais devant le Royaume-Uni (+19%), la France (+17%), l\u2019Italie (+16%), l\u2019Espagne (+11%), la Pologne (+11%) ou la Hongrie (+5%).<\/p>\n<p>Ailleurs dans le monde, la Pr\u00e9vision Nette d\u2019Emploi atteint +30% aux \u00c9tats-Unis, +28% en Chine et +15% au Japon.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14326 size-large\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-1024x1024.png\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-1024x1024.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-300x300.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-150x150.png 150w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-768x768.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-146x146.png 146w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-50x50.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-75x75.png 75w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-85x85.png 85w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR-80x80.png 80w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/9_Global_-Outlook_-Q325_-BEFR.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Les <\/em><\/strong><strong><em>r\u00e9sultats de la prochaine \u00e9dition du Barom\u00e8tre ManpowerGroup des perspectives d\u2019emploi seront diffus\u00e9s le\u00a09 septembre 2025 (4e trimestre 2025).<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>(1) La valeur de la Pr\u00e9vision Nette d&rsquo;Emploi est obtenue en d\u00e9duisant du pourcentage des employeurs anticipant une hausse de l&#8217;emploi total, le pourcentage des employeurs pr\u00e9voyant une baisse de l&#8217;emploi dans leur entreprise pour le trimestre suivant. Il s&rsquo;agit donc ici du solde net des pr\u00e9visions d&#8217;emploi, qui peut \u00eatre aussi bien positif que n\u00e9gatif. Les commentaires se basent sur les donn\u00e9es d\u00e9saisonnalis\u00e9es, lorsqu\u2019elles sont disponibles.<\/p>\n<p>&nbsp;<\/p>\n<h2>\u00c0 propos du Barom\u00e8tre de l\u2019emploi de ManpowerGroup<\/h2>\n<p>Le Barom\u00e8tre ManpowerGroup des Perspectives d\u2019Emploi (ManpowerGroup Employment Outlook Survey &#8211; MEOS) pour le\u00a0 3e trimestre 2025 a \u00e9t\u00e9 men\u00e9 en avril 2025\u00a0 aupr\u00e8s d\u2019un \u00e9chantillon repr\u00e9sentatif de 40.000 employeurs publics et priv\u00e9s (dont 525 en Belgique) dans 41 pays et territoires. L\u2019objectif de l\u2019enqu\u00eate est de mesurer l\u2019\u00e9volution des intentions de recrutement des entreprises pour le trimestre \u00e0 venir et par rapport au trimestre pr\u00e9c\u00e9dent. Chaque employeur interrog\u00e9 a r\u00e9pondu \u00e0 la m\u00eame question : <strong>\u00ab\u00a0Comment anticipez-vous l\u2019\u00e9volution de l\u2019emploi total dans votre entreprise au cours du prochain trimestre, c&rsquo;est-\u00e0-dire jusqu\u2019\u00e0 fin septembre 2025, par rapport au trimestre actuel ?\u00a0\u00bb.<\/strong> C\u2019est la seule \u00e9tude prospective de cette envergure dans le domaine de l\u2019emploi. Elle est unique par sa taille, son objectif, sa long\u00e9vit\u00e9 et son contenu. Men\u00e9 depuis 60 ans, le Barom\u00e8tre ManpowerGroup constitue l\u2019une des enqu\u00eates les plus fiables en mati\u00e8re d\u2019emploi et est consid\u00e9r\u00e9 comme un indicateur \u00e9conomique reconnu.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/BE_MEOS_carousel_FR.pdf\" target=\"_blank\" rel=\"noopener\">Rapport : Barom\u00e8tre de l&#8217;emploi de ManpowerGroup Q3\/2025<\/a><\/h2>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/BE_MEOS_carousel_FR.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14329 size-medium\" src=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-300x300.png 300w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-1024x1024.png 1024w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-150x150.png 150w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-768x768.png 768w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-146x146.png 146w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-50x50.png 50w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-75x75.png 75w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-85x85.png 85w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR-80x80.png 80w, https:\/\/manpowergroup.be\/wp-content\/uploads\/2025\/06\/1_meos-_Q325_-BEFR.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Pr\u00e9vision Nette d\u2019Emploi pour le 3e trimestre 2025 chute \u00e0 +20% \u2013 son niveau le plus bas depuis deux ans \u2013 , tandis que l\u2019incertitude<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":3,"featured_media":14365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[24],"tags":[811,345],"class_list":["post-14309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-barometre-de-lemploi-de-manpowergroup","tag-perspectives-d-emploi"],"_links":{"self":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/14309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/comments?post=14309"}],"version-history":[{"count":3,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/14309\/revisions"}],"predecessor-version":[{"id":14371,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/posts\/14309\/revisions\/14371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/media\/14365"}],"wp:attachment":[{"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/media?parent=14309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/categories?post=14309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manpowergroup.be\/fr\/wp-json\/wp\/v2\/tags?post=14309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}